{"id":42408,"date":"2025-06-12T15:30:32","date_gmt":"2025-06-12T19:30:32","guid":{"rendered":"https:\/\/ko3g503ir7-staging.onrocket.site\/solicitacao-de-dupla-cidadania-em-luxemburgo\/"},"modified":"2025-06-19T23:16:44","modified_gmt":"2025-06-20T03:16:44","slug":"solicitacao-de-dupla-cidadania-em-luxemburgo","status":"publish","type":"page","link":"https:\/\/www.luxcitizenship.com\/br\/solicitacao-de-dupla-cidadania-em-luxemburgo\/","title":{"rendered":"Solicita\u00e7\u00e3o de dupla cidadania em Luxemburgo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Veja as fotos dos clientes da LuxCitizenship ap\u00f3s solicitarem a dupla cidadania luxemburguesa no Bierger-Center, na cidade de Luxemburgo.<\/p>\n<ul data-count=\"45\" class=\"wp-block-gallery alignundefined columns-3 is-cropped\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Image.jpg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"1333\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Image.jpg\" alt=\"Image\" data-id=\"40529\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/image-3-2\/\" class=\"wp-image-40529\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Image.jpg 1000w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Image-225x300.jpg 225w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Image-768x1024.jpg 768w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Image-300x400.jpg 300w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/229668535_1215597265579685_8498061875120263415_n.jpg\"><img decoding=\"async\" width=\"720\" height=\"540\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/229668535_1215597265579685_8498061875120263415_n.jpg\" alt=\"229668535_1215597265579685_8498061875120263415_n\" data-id=\"40527\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/229668535_1215597265579685_8498061875120263415_n-2-2\/\" class=\"wp-image-40527\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/229668535_1215597265579685_8498061875120263415_n.jpg 720w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/229668535_1215597265579685_8498061875120263415_n-300x225.jpg 300w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/231182820_1216238178848927_5156139933266110602_n.jpg\"><img decoding=\"async\" width=\"720\" height=\"540\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/231182820_1216238178848927_5156139933266110602_n.jpg\" alt=\"231182820_1216238178848927_5156139933266110602_n\" data-id=\"40525\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/231182820_1216238178848927_5156139933266110602_n-2-2\/\" class=\"wp-image-40525\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/231182820_1216238178848927_5156139933266110602_n.jpg 720w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/231182820_1216238178848927_5156139933266110602_n-300x225.jpg 300w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/231258641_1216237432182335_4430589579804728162_n.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/231258641_1216237432182335_4430589579804728162_n.jpg\" alt=\"231258641_1216237432182335_4430589579804728162_n\" data-id=\"40523\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/231258641_1216237432182335_4430589579804728162_n-2-2\/\" class=\"wp-image-40523\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/231258641_1216237432182335_4430589579804728162_n.jpg 720w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/231258641_1216237432182335_4430589579804728162_n-300x225.jpg 300w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/279010752_1381833758956034_944535652470062057_n.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1264\" height=\"1000\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/279010752_1381833758956034_944535652470062057_n.jpg\" alt=\"279010752_1381833758956034_944535652470062057_n\" data-id=\"40521\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/279010752_1381833758956034_944535652470062057_n-2\/\" class=\"wp-image-40521\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/279010752_1381833758956034_944535652470062057_n.jpg 1264w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/279010752_1381833758956034_944535652470062057_n-300x237.jpg 300w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/279010752_1381833758956034_944535652470062057_n-1024x810.jpg 1024w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/279010752_1381833758956034_944535652470062057_n-768x608.jpg 768w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/279010752_1381833758956034_944535652470062057_n-1200x949.jpg 1200w\" sizes=\"(max-width: 1264px) 100vw, 1264px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/296033706_492999722826179_955078007883247539_n.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1332\" height=\"1000\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/296033706_492999722826179_955078007883247539_n.jpg\" alt=\"296033706_492999722826179_955078007883247539_n\" data-id=\"40519\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/296033706_492999722826179_955078007883247539_n-2\/\" class=\"wp-image-40519\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/296033706_492999722826179_955078007883247539_n.jpg 1332w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/296033706_492999722826179_955078007883247539_n-300x225.jpg 300w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/296033706_492999722826179_955078007883247539_n-1024x769.jpg 1024w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/296033706_492999722826179_955078007883247539_n-768x577.jpg 768w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/296033706_492999722826179_955078007883247539_n-1200x901.jpg 1200w\" sizes=\"(max-width: 1332px) 100vw, 1332px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Bierger-Center-1-scaled-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1333\" height=\"1000\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Bierger-Center-1-scaled-1.jpg\" alt=\"Bierger-Center-1-scaled\" data-id=\"40517\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/bierger-center-1-scaled-2\/\" class=\"wp-image-40517\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Bierger-Center-1-scaled-1.jpg 1333w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Bierger-Center-1-scaled-1-300x225.jpg 300w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Bierger-Center-1-scaled-1-1024x768.jpg 1024w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Bierger-Center-1-scaled-1-768x576.jpg 768w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Bierger-Center-1-scaled-1-1200x900.jpg 1200w\" sizes=\"(max-width: 1333px) 100vw, 1333px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Client-declaration-6-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"690\" height=\"604\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Client-declaration-6-1.jpg\" alt=\"Client-declaration-6\" data-id=\"40515\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/client-declaration-6-3-2\/\" class=\"wp-image-40515\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Client-declaration-6-1.jpg 690w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Client-declaration-6-1-300x263.jpg 300w\" sizes=\"(max-width: 690px) 100vw, 690px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/family-declaration-BC.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"586\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/family-declaration-BC.jpg\" alt=\"family-declaration-BC\" data-id=\"40513\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/family-declaration-bc-2-2\/\" class=\"wp-image-40513\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/family-declaration-BC.jpg 700w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/family-declaration-BC-300x251.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/family-luke.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/family-luke.jpg\" alt=\"family-luke\" data-id=\"40511\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/family-luke-2-2\/\" class=\"wp-image-40511\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/family-luke.jpg 1000w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/family-luke-300x300.jpg 300w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/family-luke-150x150.jpg 150w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/family-luke-768x768.jpg 768w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/family-luke-600x600.jpg 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/FB_IMG_1720794780987-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1040\" height=\"1310\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/FB_IMG_1720794780987-1.jpg\" alt=\"FB_IMG_1720794780987-1\" data-id=\"40509\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/fb_img_1720794780987-1-2\/\" class=\"wp-image-40509\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/FB_IMG_1720794780987-1.jpg 1040w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/FB_IMG_1720794780987-1-238x300.jpg 238w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/FB_IMG_1720794780987-1-813x1024.jpg 813w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/FB_IMG_1720794780987-1-768x967.jpg 768w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/FB_IMG_1720794780987-1-300x378.jpg 300w\" sizes=\"(max-width: 1040px) 100vw, 1040px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/holiday-travel.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/holiday-travel.jpg\" alt=\"mother and two children stand in front of christmas tree in Luxembourg\" data-id=\"40507\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/holiday-travel-2-2\/\" class=\"wp-image-40507\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/holiday-travel.jpg 1000w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/holiday-travel-300x300.jpg 300w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/holiday-travel-150x150.jpg 150w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/holiday-travel-768x768.jpg 768w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/holiday-travel-600x600.jpg 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/image_67178241-scaled-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1333\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/image_67178241-scaled-1.jpg\" alt=\"image_67178241-scaled\" data-id=\"40505\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/image_67178241-scaled-2\/\" class=\"wp-image-40505\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/image_67178241-scaled-1.jpg 1000w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/image_67178241-scaled-1-225x300.jpg 225w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/image_67178241-scaled-1-768x1024.jpg 768w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/image_67178241-scaled-1-300x400.jpg 300w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Image-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Image-1.jpg\" alt=\"Image-1\" data-id=\"40503\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/image-1-2\/\" class=\"wp-image-40503\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Image-1.jpg 1000w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Image-1-300x300.jpg 300w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Image-1-150x150.jpg 150w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Image-1-768x768.jpg 768w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Image-1-600x600.jpg 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Image-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Image-2.jpg\" alt=\"Image-2\" data-id=\"40501\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/image-2-2\/\" class=\"wp-image-40501\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Image-2.jpg 1000w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Image-2-300x300.jpg 300w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Image-2-150x150.jpg 150w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Image-2-768x768.jpg 768w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Image-2-600x600.jpg 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/image0-copy-3-rotated-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"480\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/image0-copy-3-rotated-1.jpg\" alt=\"image0-copy-3-rotated\" data-id=\"40499\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/image0-copy-3-rotated-2\/\" class=\"wp-image-40499\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/image0-copy-3-rotated-1.jpg 640w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/image0-copy-3-rotated-1-300x225.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/image4-rotated-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1280\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/image4-rotated-1.jpg\" alt=\"image4-rotated\" data-id=\"40497\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/image4-rotated-2\/\" class=\"wp-image-40497\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/image4-rotated-1.jpg 960w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/image4-rotated-1-225x300.jpg 225w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/image4-rotated-1-768x1024.jpg 768w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/image4-rotated-1-300x400.jpg 300w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_0032-public.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_0032-public.jpg\" alt=\"IMG_0032-public\" data-id=\"40495\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/img_0032-public-2\/\" class=\"wp-image-40495\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_0032-public.jpg 600w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_0032-public-300x300.jpg 300w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_0032-public-150x150.jpg 150w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_0126-scaled-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1333\" height=\"1000\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_0126-scaled-1.jpg\" alt=\"IMG_0126-scaled\" data-id=\"40493\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/img_0126-scaled-2\/\" class=\"wp-image-40493\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_0126-scaled-1.jpg 1333w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_0126-scaled-1-300x225.jpg 300w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_0126-scaled-1-1024x768.jpg 1024w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_0126-scaled-1-768x576.jpg 768w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_0126-scaled-1-1200x900.jpg 1200w\" sizes=\"(max-width: 1333px) 100vw, 1333px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_1138-scaled-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1333\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_1138-scaled-1.jpg\" alt=\"IMG_1138-scaled\" data-id=\"40491\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/img_1138-scaled-2\/\" class=\"wp-image-40491\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_1138-scaled-1.jpg 1000w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_1138-scaled-1-225x300.jpg 225w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_1138-scaled-1-768x1024.jpg 768w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_1138-scaled-1-300x400.jpg 300w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_1388-2-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1918\" height=\"1000\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_1388-2-1.jpg\" alt=\"IMG_1388-2-1\" data-id=\"40489\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/img_1388-2-1-2-2\/\" class=\"wp-image-40489\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_1388-2-1.jpg 1918w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_1388-2-1-300x156.jpg 300w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_1388-2-1-1024x534.jpg 1024w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_1388-2-1-768x400.jpg 768w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_1388-2-1-1536x801.jpg 1536w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_1388-2-1-1200x626.jpg 1200w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_1388-2-1-1400x730.jpg 1400w\" sizes=\"(max-width: 1918px) 100vw, 1918px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_2782.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1333\" height=\"1000\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_2782.jpg\" alt=\"IMG_2782\" data-id=\"40487\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/img_2782-2\/\" class=\"wp-image-40487\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_2782.jpg 1333w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_2782-300x225.jpg 300w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_2782-1024x768.jpg 1024w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_2782-768x576.jpg 768w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_2782-1200x900.jpg 1200w\" sizes=\"(max-width: 1333px) 100vw, 1333px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_2875.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1333\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_2875.jpg\" alt=\"IMG_2875\" data-id=\"40485\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/img_2875-2\/\" class=\"wp-image-40485\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_2875.jpg 1000w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_2875-225x300.jpg 225w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_2875-768x1024.jpg 768w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_2875-300x400.jpg 300w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_2876-rotated-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"640\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_2876-rotated-1.jpg\" alt=\"IMG_2876-rotated\" data-id=\"40483\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/img_2876-rotated-2\/\" class=\"wp-image-40483\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_2876-rotated-1.jpg 480w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_2876-rotated-1-225x300.jpg 225w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_2876-rotated-1-300x400.jpg 300w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_2920-rotated-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"640\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_2920-rotated-1.jpg\" alt=\"IMG_2920-rotated\" data-id=\"40481\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/img_2920-rotated-2\/\" class=\"wp-image-40481\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_2920-rotated-1.jpg 480w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_2920-rotated-1-225x300.jpg 225w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_2920-rotated-1-300x400.jpg 300w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_2921.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"640\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_2921.jpg\" alt=\"IMG_2921\" data-id=\"40479\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/img_2921-2-2\/\" class=\"wp-image-40479\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_2921.jpg 480w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_2921-225x300.jpg 225w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_2921-300x400.jpg 300w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_3349.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1333\" height=\"1000\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_3349.jpg\" alt=\"Smiling newly accepted Luxembourg dual citizen outside of Bierger-Center holding up official certification papers\" data-id=\"40477\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/img_3349-2-2\/\" class=\"wp-image-40477\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_3349.jpg 1333w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_3349-300x225.jpg 300w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_3349-1024x768.jpg 1024w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_3349-768x576.jpg 768w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_3349-1200x900.jpg 1200w\" sizes=\"(max-width: 1333px) 100vw, 1333px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_3572.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_3572.jpg\" alt=\"IMG_3572\" data-id=\"40475\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/img_3572-2\/\" class=\"wp-image-40475\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_3572.jpg 1024w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_3572-300x225.jpg 300w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_3572-768x576.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_3901-scaled-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1333\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_3901-scaled-1.jpg\" alt=\"IMG_3901-scaled\" data-id=\"40473\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/img_3901-scaled-2\/\" class=\"wp-image-40473\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_3901-scaled-1.jpg 1000w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_3901-scaled-1-225x300.jpg 225w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_3901-scaled-1-768x1024.jpg 768w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_3901-scaled-1-300x400.jpg 300w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_4301.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_4301.jpg\" alt=\"IMG_4301\" data-id=\"40471\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/img_4301-2\/\" class=\"wp-image-40471\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_4301.jpg 1000w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_4301-300x300.jpg 300w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_4301-150x150.jpg 150w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_4301-768x768.jpg 768w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_4301-600x600.jpg 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_7095.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"664\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_7095.jpg\" alt=\"IMG_7095\" data-id=\"40469\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/img_7095-2-2\/\" class=\"wp-image-40469\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_7095.jpg 1024w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_7095-300x195.jpg 300w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_7095-768x498.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_8368-scaled-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1333\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_8368-scaled-1.jpg\" alt=\"Three newly accepted Luxembourg dual citizens posing \" data-id=\"40467\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/img_8368-scaled-2\/\" class=\"wp-image-40467\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_8368-scaled-1.jpg 1000w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_8368-scaled-1-225x300.jpg 225w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_8368-scaled-1-768x1024.jpg 768w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_8368-scaled-1-300x400.jpg 300w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_8466-scaled-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1333\" height=\"1000\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_8466-scaled-1.jpg\" alt=\"IMG_8466-scaled\" data-id=\"40465\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/img_8466-scaled-2\/\" class=\"wp-image-40465\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_8466-scaled-1.jpg 1333w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_8466-scaled-1-300x225.jpg 300w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_8466-scaled-1-1024x768.jpg 1024w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_8466-scaled-1-768x576.jpg 768w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_8466-scaled-1-1200x900.jpg 1200w\" sizes=\"(max-width: 1333px) 100vw, 1333px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_20221122_092435-scaled-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1333\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_20221122_092435-scaled-1.jpg\" alt=\"IMG_20221122_092435-scaled\" data-id=\"40463\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/img_20221122_092435-scaled-2\/\" class=\"wp-image-40463\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_20221122_092435-scaled-1.jpg 1000w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_20221122_092435-scaled-1-225x300.jpg 225w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_20221122_092435-scaled-1-768x1024.jpg 768w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/IMG_20221122_092435-scaled-1-300x400.jpg 300w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/lori-korte-bierger-centerpublic-scaled-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/lori-korte-bierger-centerpublic-scaled-1.jpg\" alt=\"lori-korte-bierger-centerpublic-scaled\" data-id=\"40461\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/lori-korte-bierger-centerpublic-scaled-2\/\" class=\"wp-image-40461\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/lori-korte-bierger-centerpublic-scaled-1.jpg 1000w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/lori-korte-bierger-centerpublic-scaled-1-300x300.jpg 300w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/lori-korte-bierger-centerpublic-scaled-1-150x150.jpg 150w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/lori-korte-bierger-centerpublic-scaled-1-768x768.jpg 768w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/lori-korte-bierger-centerpublic-scaled-1-600x600.jpg 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/lux-declaration.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1333\" height=\"1000\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/lux-declaration.jpg\" alt=\"lux-declaration\" data-id=\"40459\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/lux-declaration-2\/\" class=\"wp-image-40459\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/lux-declaration.jpg 1333w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/lux-declaration-300x225.jpg 300w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/lux-declaration-1024x768.jpg 1024w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/lux-declaration-768x576.jpg 768w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/lux-declaration-1200x900.jpg 1200w\" sizes=\"(max-width: 1333px) 100vw, 1333px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Nichole-Declaration-Banner.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"828\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Nichole-Declaration-Banner.jpg\" alt=\"Nichole-Declaration-Banner\" data-id=\"40457\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/nichole-declaration-banner-2-2\/\" class=\"wp-image-40457\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Nichole-Declaration-Banner.jpg 2000w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Nichole-Declaration-Banner-300x124.jpg 300w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Nichole-Declaration-Banner-1024x424.jpg 1024w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Nichole-Declaration-Banner-768x318.jpg 768w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Nichole-Declaration-Banner-1536x636.jpg 1536w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Nichole-Declaration-Banner-1200x497.jpg 1200w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Nichole-Declaration-Banner-1400x580.jpg 1400w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/original-95D20C0E-D498-4B4F-B88A-4552B674F9E1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1333\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/original-95D20C0E-D498-4B4F-B88A-4552B674F9E1.jpg\" alt=\"original-95D20C0E-D498-4B4F-B88A-4552B674F9E1\" data-id=\"40455\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/original-95d20c0e-d498-4b4f-b88a-4552b674f9e1-2\/\" class=\"wp-image-40455\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/original-95D20C0E-D498-4B4F-B88A-4552B674F9E1.jpg 1000w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/original-95D20C0E-D498-4B4F-B88A-4552B674F9E1-225x300.jpg 225w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/original-95D20C0E-D498-4B4F-B88A-4552B674F9E1-768x1024.jpg 768w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/original-95D20C0E-D498-4B4F-B88A-4552B674F9E1-300x400.jpg 300w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/outsideBiergerCenter.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"600\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/outsideBiergerCenter.jpg\" alt=\"outsideBiergerCenter\" data-id=\"40453\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/outsidebiergercenter-2\/\" class=\"wp-image-40453\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/outsideBiergerCenter.jpg 450w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/outsideBiergerCenter-225x300.jpg 225w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/outsideBiergerCenter-300x400.jpg 300w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/PXL_20220330_142201858.PORTRAIT-scaled-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1328\" height=\"1000\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/PXL_20220330_142201858.PORTRAIT-scaled-1.jpg\" alt=\"PXL_20220330_142201858.PORTRAIT-scaled\" data-id=\"40451\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/pxl_20220330_142201858-portrait-scaled-2\/\" class=\"wp-image-40451\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/PXL_20220330_142201858.PORTRAIT-scaled-1.jpg 1328w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/PXL_20220330_142201858.PORTRAIT-scaled-1-300x226.jpg 300w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/PXL_20220330_142201858.PORTRAIT-scaled-1-1024x771.jpg 1024w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/PXL_20220330_142201858.PORTRAIT-scaled-1-768x578.jpg 768w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/PXL_20220330_142201858.PORTRAIT-scaled-1-1200x904.jpg 1200w\" sizes=\"(max-width: 1328px) 100vw, 1328px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/PXL_20220523_080020640-scaled-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1328\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/PXL_20220523_080020640-scaled-1.jpg\" alt=\"PXL_20220523_080020640-scaled\" data-id=\"40449\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/pxl_20220523_080020640-scaled-2\/\" class=\"wp-image-40449\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/PXL_20220523_080020640-scaled-1.jpg 1000w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/PXL_20220523_080020640-scaled-1-226x300.jpg 226w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/PXL_20220523_080020640-scaled-1-771x1024.jpg 771w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/PXL_20220523_080020640-scaled-1-768x1020.jpg 768w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/PXL_20220523_080020640-scaled-1-300x398.jpg 300w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/PXL_20230728_084650496-scaled-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1333\" height=\"1000\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/PXL_20230728_084650496-scaled-1.jpg\" alt=\"PXL_20230728_084650496-scaled\" data-id=\"40447\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/pxl_20230728_084650496-scaled-2\/\" class=\"wp-image-40447\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/PXL_20230728_084650496-scaled-1.jpg 1333w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/PXL_20230728_084650496-scaled-1-300x225.jpg 300w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/PXL_20230728_084650496-scaled-1-1024x768.jpg 1024w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/PXL_20230728_084650496-scaled-1-768x576.jpg 768w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/PXL_20230728_084650496-scaled-1-1200x900.jpg 1200w\" sizes=\"(max-width: 1333px) 100vw, 1333px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/S-Declaration-Crop.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1333\" height=\"1000\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/S-Declaration-Crop.jpg\" alt=\"S-Declaration-Crop\" data-id=\"40445\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/s-declaration-crop-2-2\/\" class=\"wp-image-40445\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/S-Declaration-Crop.jpg 1333w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/S-Declaration-Crop-300x225.jpg 300w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/S-Declaration-Crop-1024x768.jpg 1024w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/S-Declaration-Crop-768x576.jpg 768w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/S-Declaration-Crop-1200x900.jpg 1200w\" sizes=\"(max-width: 1333px) 100vw, 1333px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Two-New-Lux-Citizens-almost-003-scaled-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1333\" height=\"1000\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Two-New-Lux-Citizens-almost-003-scaled-1.jpg\" alt=\"Two-New-Lux-Citizens-almost-003-scaled\" data-id=\"40443\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/two-new-lux-citizens-almost-003-scaled-2\/\" class=\"wp-image-40443\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Two-New-Lux-Citizens-almost-003-scaled-1.jpg 1333w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Two-New-Lux-Citizens-almost-003-scaled-1-300x225.jpg 300w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Two-New-Lux-Citizens-almost-003-scaled-1-1024x768.jpg 1024w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Two-New-Lux-Citizens-almost-003-scaled-1-768x576.jpg 768w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Two-New-Lux-Citizens-almost-003-scaled-1-1200x900.jpg 1200w\" sizes=\"(max-width: 1333px) 100vw, 1333px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Nospelt-Client.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"602\" height=\"732\" src=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Nospelt-Client.jpg\" alt=\"Nospelt-Client\" data-id=\"40441\" data-link=\"https:\/\/www.luxcitizenship.com\/br\/nospelt-client-2-2\/\" class=\"wp-image-40441\" srcset=\"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Nospelt-Client.jpg 602w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Nospelt-Client-247x300.jpg 247w, https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/06\/Nospelt-Client-300x365.jpg 300w\" sizes=\"(max-width: 602px) 100vw, 602px\" \/><\/a><\/figure><\/li><\/ul>","protected":false},"excerpt":{"rendered":"<p>Veja as fotos dos clientes da LuxCitizenship ap\u00f3s solicitarem a dupla cidadania luxemburguesa no Bierger-Center, na cidade de Luxemburgo.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_genesis_block_theme_hide_title":false,"footnotes":""},"tags":[],"class_list":["post-42408","page","type-page","status-publish","hentry","post","without-featured-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Solicita\u00e7\u00e3o de dupla cidadania em Luxemburgo - LuxCitizenship<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.luxcitizenship.com\/br\/solicitacao-de-dupla-cidadania-em-luxemburgo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Solicita\u00e7\u00e3o de dupla cidadania em Luxemburgo\" \/>\n<meta property=\"og:description\" content=\"Veja as fotos dos clientes da LuxCitizenship ap\u00f3s solicitarem a dupla cidadania luxemburguesa no Bierger-Center, na cidade de Luxemburgo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.luxcitizenship.com\/br\/solicitacao-de-dupla-cidadania-em-luxemburgo\/\" \/>\n<meta property=\"og:site_name\" content=\"LuxCitizenship\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/luxcitizenship\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-20T03:16:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.luxcitizenship.com\\\/br\\\/solicitacao-de-dupla-cidadania-em-luxemburgo\\\/\",\"url\":\"https:\\\/\\\/www.luxcitizenship.com\\\/br\\\/solicitacao-de-dupla-cidadania-em-luxemburgo\\\/\",\"name\":\"Solicita\u00e7\u00e3o de dupla cidadania em Luxemburgo - LuxCitizenship\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.luxcitizenship.com\\\/br\\\/#website\"},\"datePublished\":\"2025-06-12T19:30:32+00:00\",\"dateModified\":\"2025-06-20T03:16:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.luxcitizenship.com\\\/br\\\/solicitacao-de-dupla-cidadania-em-luxemburgo\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.luxcitizenship.com\\\/br\\\/solicitacao-de-dupla-cidadania-em-luxemburgo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.luxcitizenship.com\\\/br\\\/solicitacao-de-dupla-cidadania-em-luxemburgo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.luxcitizenship.com\\\/br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Solicita\u00e7\u00e3o de dupla cidadania em Luxemburgo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.luxcitizenship.com\\\/br\\\/#website\",\"url\":\"https:\\\/\\\/www.luxcitizenship.com\\\/br\\\/\",\"name\":\"LuxCitizenship\",\"description\":\"LuxCitizenship guides individuals worldwide in reclaiming Luxembourg dual citizenship through ancestry, offering expert support and fostering a global community.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.luxcitizenship.com\\\/br\\\/#organization\"},\"alternateName\":\"luxcitizenship.com\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.luxcitizenship.com\\\/br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.luxcitizenship.com\\\/br\\\/#organization\",\"name\":\"LuxCitizenship\",\"alternateName\":\"Lux Citizenship\",\"url\":\"https:\\\/\\\/www.luxcitizenship.com\\\/br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.luxcitizenship.com\\\/br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.luxcitizenship.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-LuxCitizenship-scaled.png\",\"contentUrl\":\"https:\\\/\\\/www.luxcitizenship.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Logo-LuxCitizenship-scaled.png\",\"width\":2560,\"height\":340,\"caption\":\"LuxCitizenship\"},\"image\":{\"@id\":\"https:\\\/\\\/www.luxcitizenship.com\\\/br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/luxcitizenship\\\/\",\"https:\\\/\\\/www.instagram.com\\\/lux.citizenship\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/76830834\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCyNFiM2LEdudlH_icjmfNKg\"],\"founder\":{\"@id\":\"https:\\\/\\\/danielatz.com\\\/#person\"},\"foundingDate\":\"2016\",\"address\":{\"@type\":\"PostalAddress\",\"streetAddress\":\"500 7th Avenue, Floor 8\",\"addressLocality\":\"New York\",\"addressRegion\":\"NY\",\"postalCode\":\"10018\",\"addressCountry\":\"US\"},\"parentOrganization\":{\"@type\":\"Organization\",\"name\":\"Connaissance Solutions LLC\",\"url\":\"https:\\\/\\\/connaissance.co\\\/\"},\"description\":\"Whether you\u2019re seeking citizenship, community, or a deeper connection to your heritage, LuxCitizenship is here to help you every step of the way.\",\"email\":\"info@luxcitizenship.com\",\"telephone\":\"(917) 740-8908\",\"legalName\":\"Connaissance Solutions LLC\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Solicita\u00e7\u00e3o de dupla cidadania em Luxemburgo - LuxCitizenship","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.luxcitizenship.com\/br\/solicitacao-de-dupla-cidadania-em-luxemburgo\/","og_locale":"pt_BR","og_type":"article","og_title":"Solicita\u00e7\u00e3o de dupla cidadania em Luxemburgo","og_description":"Veja as fotos dos clientes da LuxCitizenship ap\u00f3s solicitarem a dupla cidadania luxemburguesa no Bierger-Center, na cidade de Luxemburgo.","og_url":"https:\/\/www.luxcitizenship.com\/br\/solicitacao-de-dupla-cidadania-em-luxemburgo\/","og_site_name":"LuxCitizenship","article_publisher":"https:\/\/www.facebook.com\/luxcitizenship\/","article_modified_time":"2025-06-20T03:16:44+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.luxcitizenship.com\/br\/solicitacao-de-dupla-cidadania-em-luxemburgo\/","url":"https:\/\/www.luxcitizenship.com\/br\/solicitacao-de-dupla-cidadania-em-luxemburgo\/","name":"Solicita\u00e7\u00e3o de dupla cidadania em Luxemburgo - LuxCitizenship","isPartOf":{"@id":"https:\/\/www.luxcitizenship.com\/br\/#website"},"datePublished":"2025-06-12T19:30:32+00:00","dateModified":"2025-06-20T03:16:44+00:00","breadcrumb":{"@id":"https:\/\/www.luxcitizenship.com\/br\/solicitacao-de-dupla-cidadania-em-luxemburgo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.luxcitizenship.com\/br\/solicitacao-de-dupla-cidadania-em-luxemburgo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.luxcitizenship.com\/br\/solicitacao-de-dupla-cidadania-em-luxemburgo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.luxcitizenship.com\/br\/"},{"@type":"ListItem","position":2,"name":"Solicita\u00e7\u00e3o de dupla cidadania em Luxemburgo"}]},{"@type":"WebSite","@id":"https:\/\/www.luxcitizenship.com\/br\/#website","url":"https:\/\/www.luxcitizenship.com\/br\/","name":"LuxCitizenship","description":"LuxCitizenship guides individuals worldwide in reclaiming Luxembourg dual citizenship through ancestry, offering expert support and fostering a global community.","publisher":{"@id":"https:\/\/www.luxcitizenship.com\/br\/#organization"},"alternateName":"luxcitizenship.com","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.luxcitizenship.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.luxcitizenship.com\/br\/#organization","name":"LuxCitizenship","alternateName":"Lux Citizenship","url":"https:\/\/www.luxcitizenship.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.luxcitizenship.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/07\/Logo-LuxCitizenship-scaled.png","contentUrl":"https:\/\/www.luxcitizenship.com\/wp-content\/uploads\/2025\/07\/Logo-LuxCitizenship-scaled.png","width":2560,"height":340,"caption":"LuxCitizenship"},"image":{"@id":"https:\/\/www.luxcitizenship.com\/br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/luxcitizenship\/","https:\/\/www.instagram.com\/lux.citizenship\/","https:\/\/www.linkedin.com\/company\/76830834","https:\/\/www.youtube.com\/channel\/UCyNFiM2LEdudlH_icjmfNKg"],"founder":{"@id":"https:\/\/danielatz.com\/#person"},"foundingDate":"2016","address":{"@type":"PostalAddress","streetAddress":"500 7th Avenue, Floor 8","addressLocality":"New York","addressRegion":"NY","postalCode":"10018","addressCountry":"US"},"parentOrganization":{"@type":"Organization","name":"Connaissance Solutions LLC","url":"https:\/\/connaissance.co\/"},"description":"Whether you\u2019re seeking citizenship, community, or a deeper connection to your heritage, LuxCitizenship is here to help you every step of the way.","email":"info@luxcitizenship.com","telephone":"(917) 740-8908","legalName":"Connaissance Solutions LLC","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"}}]}},"featured_image_src":null,"featured_image_src_square":null,"_links":{"self":[{"href":"https:\/\/www.luxcitizenship.com\/br\/wp-json\/wp\/v2\/pages\/42408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.luxcitizenship.com\/br\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.luxcitizenship.com\/br\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.luxcitizenship.com\/br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.luxcitizenship.com\/br\/wp-json\/wp\/v2\/comments?post=42408"}],"version-history":[{"count":0,"href":"https:\/\/www.luxcitizenship.com\/br\/wp-json\/wp\/v2\/pages\/42408\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.luxcitizenship.com\/br\/wp-json\/wp\/v2\/media?parent=42408"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.luxcitizenship.com\/br\/wp-json\/wp\/v2\/tags?post=42408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}